{"id":962,"date":"2016-06-25T10:52:36","date_gmt":"2016-06-25T08:52:36","guid":{"rendered":"http:\/\/www.brettl.at\/blog\/?p=962"},"modified":"2024-09-02T16:46:54","modified_gmt":"2024-09-02T14:46:54","slug":"arbeitswanderung-nach-deutschland","status":"publish","type":"post","link":"https:\/\/www.brettl.at\/blog\/arbeitswanderung-nach-deutschland\/","title":{"rendered":"Arbeitswanderung nach Deutschland"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-padding-right:0px;--awb-padding-bottom:20px;--awb-padding-left:0px;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Nach dem \u201eJuliabkommen\u201c zwischen \u00d6sterreich und Deutschland wurden hunderte arbeitslose burgenl\u00e4ndische Bau- und Landarbeiter von den Arbeits\u00e4mtern als \u201eGastarbeiter\u201c nach Deutschland vermittelt. Dies entlastete den \u00f6sterreichischen Arbeitsmarkt und brachte Deutschland Arbeitskr\u00e4fte, die dort fehlten. Die Tatsache, endlich wieder Arbeit gefunden zu haben, und die gezielte Propaganda des NS-Regimes in Deutschland verfehlten ihre Wirkung bei den \u201eGastarbeitern\u201c nicht. Die meisten erz\u00e4hlten nach ihrer R\u00fcckkehr in die Heimat mit Begeisterung von den Aufbauleistungen des NS-Regimes und von den Vorteilen des Nationalsozialismus.<\/p>\n<div id=\"attachment_963\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-963\" class=\"size-medium wp-image-963\" src=\"http:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein-300x190.jpg\" alt=\"Hornstein\" width=\"300\" height=\"190\" srcset=\"https:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein-300x190.jpg 300w, https:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein-320x202.jpg 320w, https:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein-700x441.jpg 700w, https:\/\/www.brettl.at\/wp-content\/uploads\/2016\/06\/Gruppe-Hornstein.jpg 794w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-963\" class=\"wp-caption-text\">Eine Gruppe aus Hornstein als Gastarbeiter 1937 in Berchtesgaden \u00a9 ARGE Heimatarchiv Hornstein<\/p><\/div>\n<p>In einem Bericht des Gendarmeriekommandos Rudersdorf an die BH Jennersdorf vom 16. J\u00e4nner 1936 hei\u00dft es dazu:<br \/>\n\u201eDer Andrang zur Vermittlung nach Deutschland als Wanderarbeiter ist aus folgenden Gr\u00fcnden seit dem Vorjahre in diesem Umfang angewachsen: Die Ersparnisse w\u00e4hrend der Arbeitsperiode ergeben durch den W\u00e4hrungsunterschied beim \u00dcberweisungsverkehr einen gr\u00f6sseren Betrag in der Schillingw\u00e4hrung, als die bei der Besch\u00e4ftigung im Inlande erzielten Ersparnisse. Die Arbeitszeit ist in Deutschland von 6 bis 18 Uhr und wo sich die Notwendigkeit einer Mehrarbeit ergibt, werden die \u00dcberstunden mit den festgesetzten L\u00f6hnen bezahlt. Die Unterk\u00fcnfte sind meist besser als jene der Wanderarbeiter im Inlande und sind getrennte Unterk\u00fcnfte f\u00fcr M\u00e4nnliche, f\u00fcr Weibliche und f\u00fcr Verheiratete \u00fcberall vorhanden. Es ist dort das Geld etwas leichter zu verdienen, als im Inlande, weil zumeist gute Maschinen- und Betriebseinrichtungen vorhanden sind, die die Arbeit erleichtern [\u2026]. Der H\u00e4usler [\u2026] war mit seiner Gattin und 3 Kindern im Jahre 1937 auf Wanderarbeit in Deutschland. Dieser konnte einen wesentlichen Teil seiner Schulden abtragen und wenn er noch 2 mal mit den Angeh\u00f6ri\u00adgen zu dieser Arbeit ausreisen darf, ist er vollkommen saniert [\u2026].&#8221; (Bayer; Szorger: Der Weg zum Anschluss, 2008, S. 46)<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nach dem \u201eJuliabkommen\u201c zwischen \u00d6sterreich und Deutschland wurden hunderte arbeitslose burgenl\u00e4ndische Bau- und Landarbeiter von den Arbeits\u00e4mtern als \u201eGastarbeiter\u201c nach Deutschland vermittelt. <\/p>\n","protected":false},"author":3,"featured_media":963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,48,61,20],"tags":[87],"class_list":["post-962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-278","category-nationalsozialismus","category-wirtschaft","category-zwischenkriegszeit","tag-rudersdorf"],"_links":{"self":[{"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":6,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":2748,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/posts\/962\/revisions\/2748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/media\/963"}],"wp:attachment":[{"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brettl.at\/blog\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}